{"id":172,"count":1,"description":"","link":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/non-alliance-airlines\/air-tahiti-nui\/","name":"Air Tahiti Nui","slug":"air-tahiti-nui","taxonomy":"category","parent":34,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/non-alliance-airlines\/air-tahiti-nui\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/172\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.verylvke.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/category\\\/airline-groups\\\/#listItem\",\"name\":\"Airline Groups\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/category\\\/airline-groups\\\/#listItem\",\"position\":2,\"name\":\"Airline Groups\",\"item\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/category\\\/airline-groups\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/category\\\/airline-groups\\\/non-alliance-airlines\\\/#listItem\",\"name\":\"Non-alliance Airlines\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/category\\\/airline-groups\\\/non-alliance-airlines\\\/#listItem\",\"position\":3,\"name\":\"Non-alliance Airlines\",\"item\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/category\\\/airline-groups\\\/non-alliance-airlines\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/category\\\/airline-groups\\\/non-alliance-airlines\\\/air-tahiti-nui\\\/#listItem\",\"name\":\"Air Tahiti Nui\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/category\\\/airline-groups\\\/#listItem\",\"name\":\"Airline Groups\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/category\\\/airline-groups\\\/non-alliance-airlines\\\/air-tahiti-nui\\\/#listItem\",\"position\":4,\"name\":\"Air Tahiti Nui\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/category\\\/airline-groups\\\/non-alliance-airlines\\\/#listItem\",\"name\":\"Non-alliance Airlines\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/172\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/172\\\/\",\"name\":\"Air Tahiti Nui | Verylvke\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/172\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/#organization\",\"name\":\"Verylvke\",\"description\":\"Expertise in loyalty programs and travel deals!\",\"url\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/\",\"name\":\"Verylvke\",\"description\":\"Expertise in loyalty programs and travel deals!\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.verylvke.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Air Tahiti Nui | Verylvke","description":"","canonical_url":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/non-alliance-airlines\/air-tahiti-nui\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.verylvke.com\/en\/wp-json\/wp\/v2\/categories\/172\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.verylvke.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.verylvke.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/#listItem","name":"Airline Groups"}},{"@type":"ListItem","@id":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/#listItem","position":2,"name":"Airline Groups","item":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/non-alliance-airlines\/#listItem","name":"Non-alliance Airlines"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.verylvke.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/non-alliance-airlines\/#listItem","position":3,"name":"Non-alliance Airlines","item":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/non-alliance-airlines\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/non-alliance-airlines\/air-tahiti-nui\/#listItem","name":"Air Tahiti Nui"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/#listItem","name":"Airline Groups"}},{"@type":"ListItem","@id":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/non-alliance-airlines\/air-tahiti-nui\/#listItem","position":4,"name":"Air Tahiti Nui","previousItem":{"@type":"ListItem","@id":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/non-alliance-airlines\/#listItem","name":"Non-alliance Airlines"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.verylvke.com\/en\/wp-json\/wp\/v2\/categories\/172\/#collectionpage","url":"https:\/\/www.verylvke.com\/en\/wp-json\/wp\/v2\/categories\/172\/","name":"Air Tahiti Nui | Verylvke","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/www.verylvke.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.verylvke.com\/en\/wp-json\/wp\/v2\/categories\/172\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.verylvke.com\/en\/#organization","name":"Verylvke","description":"Expertise in loyalty programs and travel deals!","url":"https:\/\/www.verylvke.com\/en\/"},{"@type":"WebSite","@id":"https:\/\/www.verylvke.com\/en\/#website","url":"https:\/\/www.verylvke.com\/en\/","name":"Verylvke","description":"Expertise in loyalty programs and travel deals!","inLanguage":"en-GB","publisher":{"@id":"https:\/\/www.verylvke.com\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.verylvke.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/\" title=\"Airline Groups\">Airline Groups<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/non-alliance-airlines\/\" title=\"Non-alliance Airlines\">Non-alliance Airlines<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAir Tahiti Nui\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.verylvke.com\/en"},{"label":"Airline Groups","link":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/"},{"label":"Non-alliance Airlines","link":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/non-alliance-airlines\/"},{"label":"Air Tahiti Nui","link":"https:\/\/www.verylvke.com\/en\/category\/airline-groups\/non-alliance-airlines\/air-tahiti-nui\/"}],"_links":{"self":[{"href":"https:\/\/www.verylvke.com\/en\/wp-json\/wp\/v2\/categories\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.verylvke.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.verylvke.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.verylvke.com\/en\/wp-json\/wp\/v2\/categories\/34"}],"wp:post_type":[{"href":"https:\/\/www.verylvke.com\/en\/wp-json\/wp\/v2\/posts?categories=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}